{"id":2224,"date":"2015-01-15T10:10:11","date_gmt":"2015-01-15T10:10:11","guid":{"rendered":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert.jpg"},"modified":"2016-04-28T22:55:42","modified_gmt":"2016-04-28T22:55:42","slug":"ooopskompliziert","status":"inherit","type":"attachment","link":"https:\/\/diamondshieldzapper.com\/zh-hans\/zapper%e4%bf%a1%e6%81%af\/ooopskompliziert\/","title":{"rendered":"ooopsKompliziert"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"class_list":["post-2224","attachment","type-attachment","status-inherit","hentry","no-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ooopsKompliziert - Diamond Shield Zapper<\/title>\n<meta name=\"description\" content=\"Eine \u00dcbersicht zu s\u00e4mtlichen Informationen und Funktionen rund um den Diamond Shield Zapper IE und seine Entstehungsgeschichte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diamondshieldzapper.com\/zh-hans\/zapper%e4%bf%a1%e6%81%af\/ooopskompliziert\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ooopsKompliziert - Diamond Shield Zapper\" \/>\n<meta property=\"og:description\" content=\"Eine \u00dcbersicht zu s\u00e4mtlichen Informationen und Funktionen rund um den Diamond Shield Zapper IE und seine Entstehungsgeschichte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diamondshieldzapper.com\/zh-hans\/zapper%e4%bf%a1%e6%81%af\/ooopskompliziert\/\" \/>\n<meta property=\"og:site_name\" content=\"Diamond Shield Zapper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/heilpraktiker.baklayan\/\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-28T22:55:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"725\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diamondshieldzapper.com\\\/zh-hans\\\/zapper%e4%bf%a1%e6%81%af\\\/ooopskompliziert\\\/\",\"url\":\"https:\\\/\\\/diamondshieldzapper.com\\\/zh-hans\\\/zapper%e4%bf%a1%e6%81%af\\\/ooopskompliziert\\\/\",\"name\":\"ooopsKompliziert - Diamond Shield Zapper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamondshieldzapper.com\\\/zh-hans\\\/#website\"},\"datePublished\":\"2015-01-15T10:10:11+00:00\",\"dateModified\":\"2016-04-28T22:55:42+00:00\",\"description\":\"Eine \u00dcbersicht zu s\u00e4mtlichen Informationen und Funktionen rund um den Diamond Shield Zapper IE und seine Entstehungsgeschichte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamondshieldzapper.com\\\/zh-hans\\\/zapper%e4%bf%a1%e6%81%af\\\/ooopskompliziert\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diamondshieldzapper.com\\\/zh-hans\\\/zapper%e4%bf%a1%e6%81%af\\\/ooopskompliziert\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamondshieldzapper.com\\\/zh-hans\\\/zapper%e4%bf%a1%e6%81%af\\\/ooopskompliziert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/diamondshieldzapper.com\\\/zh-hans\\\/?page_id=7561\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zapper\u4fe1\u606f\",\"item\":\"https:\\\/\\\/diamondshieldzapper.com\\\/zh-hans\\\/zapper%e4%bf%a1%e6%81%af\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ooopsKompliziert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamondshieldzapper.com\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/diamondshieldzapper.com\\\/zh-hans\\\/\",\"name\":\"Diamond Shield Zapper\",\"description\":\"einfach nur Zappen war gestern\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diamondshieldzapper.com\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ooopsKompliziert - Diamond Shield Zapper","description":"Eine \u00dcbersicht zu s\u00e4mtlichen Informationen und Funktionen rund um den Diamond Shield Zapper IE und seine Entstehungsgeschichte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diamondshieldzapper.com\/zh-hans\/zapper%e4%bf%a1%e6%81%af\/ooopskompliziert\/","og_locale":"zh_CN","og_type":"article","og_title":"ooopsKompliziert - Diamond Shield Zapper","og_description":"Eine \u00dcbersicht zu s\u00e4mtlichen Informationen und Funktionen rund um den Diamond Shield Zapper IE und seine Entstehungsgeschichte.","og_url":"https:\/\/diamondshieldzapper.com\/zh-hans\/zapper%e4%bf%a1%e6%81%af\/ooopskompliziert\/","og_site_name":"Diamond Shield Zapper","article_publisher":"https:\/\/www.facebook.com\/heilpraktiker.baklayan\/","article_modified_time":"2016-04-28T22:55:42+00:00","og_image":[{"width":600,"height":725,"url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diamondshieldzapper.com\/zh-hans\/zapper%e4%bf%a1%e6%81%af\/ooopskompliziert\/","url":"https:\/\/diamondshieldzapper.com\/zh-hans\/zapper%e4%bf%a1%e6%81%af\/ooopskompliziert\/","name":"ooopsKompliziert - Diamond Shield Zapper","isPartOf":{"@id":"https:\/\/diamondshieldzapper.com\/zh-hans\/#website"},"datePublished":"2015-01-15T10:10:11+00:00","dateModified":"2016-04-28T22:55:42+00:00","description":"Eine \u00dcbersicht zu s\u00e4mtlichen Informationen und Funktionen rund um den Diamond Shield Zapper IE und seine Entstehungsgeschichte.","breadcrumb":{"@id":"https:\/\/diamondshieldzapper.com\/zh-hans\/zapper%e4%bf%a1%e6%81%af\/ooopskompliziert\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diamondshieldzapper.com\/zh-hans\/zapper%e4%bf%a1%e6%81%af\/ooopskompliziert\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/diamondshieldzapper.com\/zh-hans\/zapper%e4%bf%a1%e6%81%af\/ooopskompliziert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/diamondshieldzapper.com\/zh-hans\/?page_id=7561"},{"@type":"ListItem","position":2,"name":"Zapper\u4fe1\u606f","item":"https:\/\/diamondshieldzapper.com\/zh-hans\/zapper%e4%bf%a1%e6%81%af\/"},{"@type":"ListItem","position":3,"name":"ooopsKompliziert"}]},{"@type":"WebSite","@id":"https:\/\/diamondshieldzapper.com\/zh-hans\/#website","url":"https:\/\/diamondshieldzapper.com\/zh-hans\/","name":"Diamond Shield Zapper","description":"einfach nur Zappen war gestern","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diamondshieldzapper.com\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"248\" height=\"300\" src=\"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-248x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-248x300.jpg 248w, https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert.jpg 600w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":725,"file":"2015\/01\/ooopsKompliziert.jpg","sizes":{"thumbnail":{"file":"ooopsKompliziert-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-150x150.jpg"},"medium":{"file":"ooopsKompliziert-248x300.jpg","width":248,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-248x300.jpg"},"blog-large":{"file":"ooopsKompliziert-600x272.jpg","width":600,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-600x272.jpg"},"blog-medium":{"file":"ooopsKompliziert-320x202.jpg","width":320,"height":202,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-320x202.jpg"},"tabs-img":{"file":"ooopsKompliziert-52x50.jpg","width":52,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-52x50.jpg"},"related-img":{"file":"ooopsKompliziert-180x138.jpg","width":180,"height":138,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-180x138.jpg"},"portfolio-full":{"file":"ooopsKompliziert-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-600x400.jpg"},"portfolio-one":{"file":"ooopsKompliziert-540x272.jpg","width":540,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-540x272.jpg"},"portfolio-two":{"file":"ooopsKompliziert-460x295.jpg","width":460,"height":295,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-460x295.jpg"},"portfolio-three":{"file":"ooopsKompliziert-300x214.jpg","width":300,"height":214,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-300x214.jpg"},"portfolio-four":{"file":"ooopsKompliziert-220x161.jpg","width":220,"height":161,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-220x161.jpg"},"portfolio-five":{"file":"ooopsKompliziert-177x142.jpg","width":177,"height":142,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-177x142.jpg"},"portfolio-six":{"file":"ooopsKompliziert-147x118.jpg","width":147,"height":118,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-147x118.jpg"},"recent-posts":{"file":"ooopsKompliziert-600x441.jpg","width":600,"height":441,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-600x441.jpg"},"recent-works-thumbnail":{"file":"ooopsKompliziert-66x66.jpg","width":66,"height":66,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-66x66.jpg"},"shop_thumbnail":{"file":"ooopsKompliziert-120x100.jpg","width":120,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-120x100.jpg"},"shop_catalog":{"file":"ooopsKompliziert-500x400.jpg","width":500,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-500x400.jpg"},"shop_single":{"file":"ooopsKompliziert-500x400.jpg","width":500,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert-500x400.jpg"},"full":{"file":"ooopsKompliziert.jpg","width":600,"height":725,"mime_type":"image\/jpeg","source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":1}},"post":2219,"source_url":"https:\/\/diamondshieldzapper.com\/wp-content\/uploads\/2015\/01\/ooopsKompliziert.jpg","filename":"ooopsKompliziert.jpg","filesize":118144,"_links":{"self":[{"href":"https:\/\/diamondshieldzapper.com\/zh-hans\/wp-json\/wp\/v2\/media\/2224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamondshieldzapper.com\/zh-hans\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/diamondshieldzapper.com\/zh-hans\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/diamondshieldzapper.com\/zh-hans\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diamondshieldzapper.com\/zh-hans\/wp-json\/wp\/v2\/comments?post=2224"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":2219,"href":"https:\/\/diamondshieldzapper.com\/zh-hans\/wp-json\/wp\/v2\/pages\/2219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}